{"id":6900,"date":"2026-03-05T22:48:28","date_gmt":"2026-03-05T22:48:28","guid":{"rendered":"https:\/\/cni.hn\/?p=6900"},"modified":"2026-03-05T22:52:02","modified_gmt":"2026-03-05T22:52:02","slug":"nucleo-espana","status":"publish","type":"post","link":"https:\/\/cni.hn\/en\/nucleo-espana\/","title":{"rendered":"N\u00facleo Espa\u00f1a"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"6900\" class=\"elementor elementor-6900\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b7ac512 e-flex e-con-boxed e-con e-parent\" data-id=\"b7ac512\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ec718f elementor-widget elementor-widget-heading\" data-id=\"3ec718f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CNI acompa\u00f1a a empresas espa\u00f1olas para fortalecer inversi\u00f3n bilateral<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dbac892 e-flex e-con-boxed e-con e-parent\" data-id=\"dbac892\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a767aa4 elementor-widget elementor-widget-text-editor\" data-id=\"a767aa4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El ministro de Inversiones, Epaminondas Marinakys, participa en reuni\u00f3n del N\u00facleo de Empresas Espa\u00f1olas en la residencia del Embajador de Espa\u00f1a para fortalecer el di\u00e1logo econ\u00f3mico y ampliar la inversi\u00f3n en el pa\u00eds.<\/p><p><strong>Tegucigalpa, 5 de marzo de 2026. \u2013<\/strong><\/p><p>Representantes de empresas espa\u00f1olas con presencia e inter\u00e9s en el mercado hondure\u00f1o sostuvieron un encuentro de alto nivel con autoridades nacionales durante la Reuni\u00f3n del N\u00facleo de Empresas Espa\u00f1olas en Honduras, realizada en Tegucigalpa, con el objetivo de analizar el clima de negocios y las perspectivas de inversi\u00f3n en el pa\u00eds.<\/p><p>El encuentro reuni\u00f3 a 19 representantes de compa\u00f1\u00edas espa\u00f1olas y cont\u00f3 con la participaci\u00f3n del ministro de Inversiones y titular del Consejo Nacional de Inversiones (CNI), Epaminondas Marinakys, quien sostuvo un primer acercamiento con el sector empresarial para conocer sus expectativas, fortalecer el di\u00e1logo institucional y explorar oportunidades para ampliar la inversi\u00f3n espa\u00f1ola en Honduras.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-67ccada e-flex e-con-boxed e-con e-parent\" data-id=\"67ccada\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b51633f elementor-widget elementor-widget-heading\" data-id=\"b51633f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Temas de agenda<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ece7f4c e-flex e-con-boxed e-con e-parent\" data-id=\"ece7f4c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-30d3300 elementor-widget elementor-widget-text-editor\" data-id=\"30d3300\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Durante la reuni\u00f3n se abordaron temas vinculados al entorno econ\u00f3mico, el fortalecimiento del n\u00facleo empresarial espa\u00f1ol en el pa\u00eds y las oportunidades que ofrece Honduras para el desarrollo de nuevos proyectos de inversi\u00f3n. La participaci\u00f3n del ministro Marinakys se enmarca en la estrategia del Gobierno del presidente Nasry Asfura, orientada a consolidar la inversi\u00f3n existente y promover la llegada de nuevas empresas internacionales.<\/p><p>En el encuentro tambi\u00e9n particip\u00f3 de manera remota el consejero econ\u00f3mico y comercial de Espa\u00f1a para la regi\u00f3n, Manuel Valle Mu\u00f1oz, quien present\u00f3 las l\u00edneas de trabajo de la red comercial espa\u00f1ola y las posibilidades de cooperaci\u00f3n econ\u00f3mica entre ambos pa\u00edses.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-89f651a e-con-full e-flex e-con e-parent\" data-id=\"89f651a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-79ea0fc elementor-widget elementor-widget-image\" data-id=\"79ea0fc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/cni.hn\/wp-content\/uploads\/2026\/03\/ministro_espana-1024x768.jpeg\" class=\"attachment-large size-large wp-image-6901\" alt=\"\" srcset=\"https:\/\/cni.hn\/wp-content\/uploads\/2026\/03\/ministro_espana-1024x768.jpeg 1024w, https:\/\/cni.hn\/wp-content\/uploads\/2026\/03\/ministro_espana-300x225.jpeg 300w, https:\/\/cni.hn\/wp-content\/uploads\/2026\/03\/ministro_espana-768x576.jpeg 768w, https:\/\/cni.hn\/wp-content\/uploads\/2026\/03\/ministro_espana-16x12.jpeg 16w, https:\/\/cni.hn\/wp-content\/uploads\/2026\/03\/ministro_espana.jpeg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b2939f6 e-flex e-con-boxed e-con e-parent\" data-id=\"b2939f6\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19ca4d6 elementor-widget elementor-widget-heading\" data-id=\"19ca4d6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Empresas espa\u00f1olas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9e2bd96 e-flex e-con-boxed e-con e-parent\" data-id=\"9e2bd96\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f0d00c elementor-widget elementor-widget-text-editor\" data-id=\"5f0d00c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Entre las empresas participantes destacaron MAPFRE Seguros, Prosegur, UFINET, Elecnor, Airtificial Intelligence Structures, Iberojet, Editorial Santillana y Gufa Law, entre otras compa\u00f1\u00edas que integran el N\u00facleo Espa\u00f1a en Honduras con el acompa\u00f1amiento de la C\u00e1mara de Comercio e Industria de Tegucigalpa (CCIT).<\/p><p>La jornada tambi\u00e9n incluy\u00f3 un reconocimiento al Embajador de Espa\u00f1a en Honduras, Diego Nu\u00f1o, por su respaldo al sector empresarial espa\u00f1ol y su contribuci\u00f3n al fortalecimiento de los v\u00ednculos econ\u00f3micos y comerciales entre Espa\u00f1a y Honduras.<\/p><p>El encuentro concluy\u00f3 con un espacio de intercambio entre autoridades y empresarios que permiti\u00f3 profundizar el di\u00e1logo sobre nuevas oportunidades de cooperaci\u00f3n econ\u00f3mica y de inversi\u00f3n entre ambos pa\u00edses.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4a4ebae e-flex e-con-boxed e-con e-parent\" data-id=\"4a4ebae\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8926a8b elementor-widget elementor-widget-heading\" data-id=\"8926a8b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Claves de la reuni\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7706d5a e-flex e-con-boxed e-con e-parent\" data-id=\"7706d5a\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d7328cd elementor-widget elementor-widget-text-editor\" data-id=\"d7328cd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 Honduras refuerza el di\u00e1logo con empresas espa\u00f1olas para consolidar y ampliar la inversi\u00f3n en el pa\u00eds.<\/p><p>\u2022 El CNI impulsa espacios de acercamiento con el sector empresarial internacional para fortalecer el clima de negocios y atraer nuevos proyectos de inversi\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>CNI acompa\u00f1a a empresas espa\u00f1olas para fortalecer inversi\u00f3n bilateral El ministro de Inversiones, Epaminondas Marinakys, participa en reuni\u00f3n del N\u00facleo de Empresas Espa\u00f1olas en la residencia del Embajador de Espa\u00f1a para fortalecer el di\u00e1logo econ\u00f3mico y ampliar la inversi\u00f3n en el pa\u00eds. Tegucigalpa, 5 de marzo de 2026. \u2013 Representantes de empresas espa\u00f1olas con presencia [&hellip;]<\/p>","protected":false},"author":2,"featured_media":6901,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"sector_relacionado":[],"class_list":["post-6900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>N\u00facleo Espa\u00f1a - CNI Honduras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cni.hn\/en\/nucleo-espana\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N\u00facleo Espa\u00f1a - CNI Honduras\" \/>\n<meta property=\"og:description\" content=\"CNI acompa\u00f1a a empresas espa\u00f1olas para fortalecer inversi\u00f3n bilateral El ministro de Inversiones, Epaminondas Marinakys, participa en reuni\u00f3n del N\u00facleo de Empresas Espa\u00f1olas en la residencia del Embajador de Espa\u00f1a para fortalecer el di\u00e1logo econ\u00f3mico y ampliar la inversi\u00f3n en el pa\u00eds. Tegucigalpa, 5 de marzo de 2026. \u2013 Representantes de empresas espa\u00f1olas con presencia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cni.hn\/en\/nucleo-espana\/\" \/>\n<meta property=\"og:site_name\" content=\"CNI Honduras\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-05T22:48:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-05T22:52:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cni.hn\/wp-content\/uploads\/2026\/03\/ministro_espana.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andres Martinez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andres Martinez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cni.hn\/nucleo-espana\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cni.hn\/nucleo-espana\/\"},\"author\":{\"name\":\"Andres Martinez\",\"@id\":\"https:\/\/cni.hn\/#\/schema\/person\/46e1e0fecbe94fa0ad734d4ec7730175\"},\"headline\":\"N\u00facleo Espa\u00f1a\",\"datePublished\":\"2026-03-05T22:48:28+00:00\",\"dateModified\":\"2026-03-05T22:52:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cni.hn\/nucleo-espana\/\"},\"wordCount\":482,\"publisher\":{\"@id\":\"https:\/\/cni.hn\/#organization\"},\"image\":{\"@id\":\"https:\/\/cni.hn\/nucleo-espana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cni.hn\/wp-content\/uploads\/2026\/03\/ministro_espana.jpeg\",\"articleSection\":[\"Sala de Prensa\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cni.hn\/nucleo-espana\/\",\"url\":\"https:\/\/cni.hn\/nucleo-espana\/\",\"name\":\"N\u00facleo Espa\u00f1a - CNI Honduras\",\"isPartOf\":{\"@id\":\"https:\/\/cni.hn\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cni.hn\/nucleo-espana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cni.hn\/nucleo-espana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cni.hn\/wp-content\/uploads\/2026\/03\/ministro_espana.jpeg\",\"datePublished\":\"2026-03-05T22:48:28+00:00\",\"dateModified\":\"2026-03-05T22:52:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cni.hn\/nucleo-espana\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cni.hn\/nucleo-espana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/cni.hn\/nucleo-espana\/#primaryimage\",\"url\":\"https:\/\/cni.hn\/wp-content\/uploads\/2026\/03\/ministro_espana.jpeg\",\"contentUrl\":\"https:\/\/cni.hn\/wp-content\/uploads\/2026\/03\/ministro_espana.jpeg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cni.hn\/nucleo-espana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cni.hn\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"N\u00facleo Espa\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cni.hn\/#website\",\"url\":\"https:\/\/cni.hn\/\",\"name\":\"CNI Honduras\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/cni.hn\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cni.hn\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cni.hn\/#organization\",\"name\":\"CNI Honduras\",\"url\":\"https:\/\/cni.hn\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/cni.hn\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cni.hn\/wp-content\/uploads\/2024\/10\/logo-cni.png\",\"contentUrl\":\"https:\/\/cni.hn\/wp-content\/uploads\/2024\/10\/logo-cni.png\",\"width\":390,\"height\":390,\"caption\":\"CNI Honduras\"},\"image\":{\"@id\":\"https:\/\/cni.hn\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cni.hn\/#\/schema\/person\/46e1e0fecbe94fa0ad734d4ec7730175\",\"name\":\"Andres Martinez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/cni.hn\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b685702cf01e6c6b2ca1586d92e9a3cef7b8c42ecb312ffa3be56699c3f1b6f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b685702cf01e6c6b2ca1586d92e9a3cef7b8c42ecb312ffa3be56699c3f1b6f6?s=96&d=mm&r=g\",\"caption\":\"Andres Martinez\"},\"url\":\"https:\/\/cni.hn\/en\/author\/amartinezcni-hn\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"N\u00facleo Espa\u00f1a - CNI Honduras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cni.hn\/en\/nucleo-espana\/","og_locale":"en_US","og_type":"article","og_title":"N\u00facleo Espa\u00f1a - CNI Honduras","og_description":"CNI acompa\u00f1a a empresas espa\u00f1olas para fortalecer inversi\u00f3n bilateral El ministro de Inversiones, Epaminondas Marinakys, participa en reuni\u00f3n del N\u00facleo de Empresas Espa\u00f1olas en la residencia del Embajador de Espa\u00f1a para fortalecer el di\u00e1logo econ\u00f3mico y ampliar la inversi\u00f3n en el pa\u00eds. Tegucigalpa, 5 de marzo de 2026. \u2013 Representantes de empresas espa\u00f1olas con presencia [&hellip;]","og_url":"https:\/\/cni.hn\/en\/nucleo-espana\/","og_site_name":"CNI Honduras","article_published_time":"2026-03-05T22:48:28+00:00","article_modified_time":"2026-03-05T22:52:02+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/cni.hn\/wp-content\/uploads\/2026\/03\/ministro_espana.jpeg","type":"image\/jpeg"}],"author":"Andres Martinez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Andres Martinez","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cni.hn\/nucleo-espana\/#article","isPartOf":{"@id":"https:\/\/cni.hn\/nucleo-espana\/"},"author":{"name":"Andres Martinez","@id":"https:\/\/cni.hn\/#\/schema\/person\/46e1e0fecbe94fa0ad734d4ec7730175"},"headline":"N\u00facleo Espa\u00f1a","datePublished":"2026-03-05T22:48:28+00:00","dateModified":"2026-03-05T22:52:02+00:00","mainEntityOfPage":{"@id":"https:\/\/cni.hn\/nucleo-espana\/"},"wordCount":482,"publisher":{"@id":"https:\/\/cni.hn\/#organization"},"image":{"@id":"https:\/\/cni.hn\/nucleo-espana\/#primaryimage"},"thumbnailUrl":"https:\/\/cni.hn\/wp-content\/uploads\/2026\/03\/ministro_espana.jpeg","articleSection":["Sala de Prensa"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/cni.hn\/nucleo-espana\/","url":"https:\/\/cni.hn\/nucleo-espana\/","name":"N\u00facleo Espa\u00f1a - CNI Honduras","isPartOf":{"@id":"https:\/\/cni.hn\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cni.hn\/nucleo-espana\/#primaryimage"},"image":{"@id":"https:\/\/cni.hn\/nucleo-espana\/#primaryimage"},"thumbnailUrl":"https:\/\/cni.hn\/wp-content\/uploads\/2026\/03\/ministro_espana.jpeg","datePublished":"2026-03-05T22:48:28+00:00","dateModified":"2026-03-05T22:52:02+00:00","breadcrumb":{"@id":"https:\/\/cni.hn\/nucleo-espana\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cni.hn\/nucleo-espana\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cni.hn\/nucleo-espana\/#primaryimage","url":"https:\/\/cni.hn\/wp-content\/uploads\/2026\/03\/ministro_espana.jpeg","contentUrl":"https:\/\/cni.hn\/wp-content\/uploads\/2026\/03\/ministro_espana.jpeg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/cni.hn\/nucleo-espana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cni.hn\/"},{"@type":"ListItem","position":2,"name":"N\u00facleo Espa\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/cni.hn\/#website","url":"https:\/\/cni.hn\/","name":"CNI Honduras","description":"","publisher":{"@id":"https:\/\/cni.hn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cni.hn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/cni.hn\/#organization","name":"CNI Honduras","url":"https:\/\/cni.hn\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cni.hn\/#\/schema\/logo\/image\/","url":"https:\/\/cni.hn\/wp-content\/uploads\/2024\/10\/logo-cni.png","contentUrl":"https:\/\/cni.hn\/wp-content\/uploads\/2024\/10\/logo-cni.png","width":390,"height":390,"caption":"CNI Honduras"},"image":{"@id":"https:\/\/cni.hn\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cni.hn\/#\/schema\/person\/46e1e0fecbe94fa0ad734d4ec7730175","name":"Andres Martinez","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cni.hn\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b685702cf01e6c6b2ca1586d92e9a3cef7b8c42ecb312ffa3be56699c3f1b6f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b685702cf01e6c6b2ca1586d92e9a3cef7b8c42ecb312ffa3be56699c3f1b6f6?s=96&d=mm&r=g","caption":"Andres Martinez"},"url":"https:\/\/cni.hn\/en\/author\/amartinezcni-hn\/"}]}},"_links":{"self":[{"href":"https:\/\/cni.hn\/en\/wp-json\/wp\/v2\/posts\/6900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cni.hn\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cni.hn\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cni.hn\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cni.hn\/en\/wp-json\/wp\/v2\/comments?post=6900"}],"version-history":[{"count":0,"href":"https:\/\/cni.hn\/en\/wp-json\/wp\/v2\/posts\/6900\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cni.hn\/en\/wp-json\/wp\/v2\/media\/6901"}],"wp:attachment":[{"href":"https:\/\/cni.hn\/en\/wp-json\/wp\/v2\/media?parent=6900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cni.hn\/en\/wp-json\/wp\/v2\/categories?post=6900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cni.hn\/en\/wp-json\/wp\/v2\/tags?post=6900"},{"taxonomy":"sector_relacionado","embeddable":true,"href":"https:\/\/cni.hn\/en\/wp-json\/wp\/v2\/sector_relacionado?post=6900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}