{"id":3516,"date":"2024-12-12T23:57:24","date_gmt":"2024-12-12T23:57:24","guid":{"rendered":"https:\/\/cni-honduras.local\/?p=3516"},"modified":"2024-12-12T23:57:24","modified_gmt":"2024-12-12T23:57:24","slug":"el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024","status":"publish","type":"post","link":"https:\/\/cni.hn\/en\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/","title":{"rendered":"El Consejo Nacional de Inversiones impulsa el desarrollo regional en la Expo Comayagua 2024"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li>El Consejo Nacional de Inversiones (CNI) impulsa su Estrategia de Enfoque Territorial para el Desarrollo en Comayagua.\u00a0<\/li>\n\n\n\n<li>La Segunda Edici\u00f3n de la Expo Comayagua<strong> <\/strong>busca impulsar el desarrollo econ\u00f3mico y social de la zona, y es organizada por la C\u00e1mara de Comercio e Industrias de Comayagua (CCICOM)<\/li>\n<\/ul>\n\n\n\n<p><strong>Comayagua, 25 de julio 2024. <\/strong>Enmarcado dentro de la Estrategia Territorial de Inversiones, el CNI desempe\u00f1a un papel fundamental en la segunda edici\u00f3n la Expo Comayagua 2024; evento de gran envergadura que se lleva a cabo del 25 al 27 de julio en la ciudad de Comayagua.&nbsp;<\/p>\n\n\n\n<p>La Expo Comayagua es una plataforma dise\u00f1ada para fomentar el intercambio comercial, atraer inversiones, fortalecer las redes de negocios y posicionar a Comayagua como un centro estrat\u00e9gico para la industria y el comercio. La feria no solo busca contribuir al crecimiento econ\u00f3mico de la regi\u00f3n, sino tambi\u00e9n crear oportunidades significativas para las empresas locales e internacionales que presentar\u00e1n sus productos y servicios a una audiencia potencial de miles de personas.&nbsp;<\/p>\n\n\n\n<p>\u00abLa Expo Comayagua 2024 es una ocasi\u00f3n \u00fanica para destacar el compromiso del CNI con el crecimiento econ\u00f3mico sostenible y la generaci\u00f3n de oportunidades de inversi\u00f3n en Honduras. Estamos orgullosos de formar parte de este evento que busca impulsar el desarrollo econ\u00f3mico y social de la regi\u00f3n\u00bb, public\u00f3 el ministro de Inversiones Miguel Medina en su cuenta de X.&nbsp;<\/p>\n\n\n\n<p>Durante la feria, el CNI presentar\u00e1 desde su stand en el pasillo ferial, las iniciativas clave que forman parte de su enfoque estrat\u00e9gico para impulsar el desarrollo regional y promover la diversificaci\u00f3n de la econom\u00eda en Honduras. La presencia activa del CNI en Expo Comayagua 2024 ofrecer\u00e1 a empresarios, inversionistas y visitantes la oportunidad de conocer de cerca las oportunidades de inversi\u00f3n disponibles en la regi\u00f3n, as\u00ed como establecer contactos con actores clave del sector econ\u00f3mico.&nbsp;<\/p>\n\n\n\n<p>La segunda edici\u00f3n de la Expo Comayagua 2024, promete ser un evento transformador para la regi\u00f3n, impulsando su desarrollo econ\u00f3mico y social; esta es organizada por la C\u00e1mara de Comercio e Industrias de Comayagua con el apoyo del CNI, Argos Honduras, Fedecamara, Ferrecomsa y Corporaci\u00f3n Dinat.<\/p>\n\n\n\n<p>El Consejo Nacional de Inversiones reafirma su compromiso de continuar trabajando en colaboraci\u00f3n con diferentes actores para fortalecer el clima de inversi\u00f3n en el pa\u00eds, contribuyendo as\u00ed\u0301 al progreso y bienestar de todas las comunidades hondure\u00f1as.&nbsp;<\/p>\n\n\n\n<p><strong>De la Estrategia de Enfoque Territorial para el Desarrollo del CNI<\/strong><\/p>\n\n\n\n<p>La Estrategia de Inversiones con Enfoque Territorial para el Desarrollo del CNI impulsa un crecimiento econ\u00f3mico equitativo y sostenible a nivel local al identificar y priorizar inversiones espec\u00edficas en \u00e1reas geogr\u00e1ficas definidas. Fomenta la colaboraci\u00f3n entre gobierno, sector privado y sociedad civil para maximizar el impacto de las inversiones y promover el desarrollo econ\u00f3mico y social de las comunidades locales.<\/p>\n\n\n\n<p>La Promoci\u00f3n Nacional de Inversiones con Enfoque Territorial busca impulsar el desarrollo econ\u00f3mico local mediante la atracci\u00f3n y gesti\u00f3n eficiente de inversiones p\u00fablicas y privadas en \u00e1reas espec\u00edficas. Esto se logra mediante la identificaci\u00f3n de oportunidades estrat\u00e9gicas, estableciendo alianzas y priorizando la competitividad, innovaci\u00f3n y sostenibilidad para generar crecimiento inclusivo, empleo, mejoras en infraestructura y calidad de vida en las \u00e1reas objetivo.<\/p>\n\n\n\n<p>Con esta estrategia se consolida la visi\u00f3n del CNI en consolidarse como la Agencia de Promoci\u00f3n e Inversiones de Honduras, que promueva y acompa\u00f1e la inversi\u00f3n nacional y extranjera, en sectores priorizados; generando fuentes de empleo para mejorar la calidad de vida.<\/p>","protected":false},"excerpt":{"rendered":"<p>Comayagua, 25 de julio 2024. Enmarcado dentro de la Estrategia Territorial de Inversiones, el CNI desempe\u00f1a un papel fundamental en la segunda edici\u00f3n la Expo Comayagua 2024; evento de gran envergadura que se lleva a cabo del 25 al 27 de julio en la ciudad de Comayagua.&nbsp; La Expo Comayagua es una plataforma dise\u00f1ada para [&hellip;]<\/p>","protected":false},"author":1,"featured_media":3517,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"sector_relacionado":[],"class_list":["post-3516","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Consejo Nacional de Inversiones impulsa el desarrollo regional en la Expo Comayagua 2024 - CNI Honduras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cni.hn\/en\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Consejo Nacional de Inversiones impulsa el desarrollo regional en la Expo Comayagua 2024 - CNI Honduras\" \/>\n<meta property=\"og:description\" content=\"Comayagua, 25 de julio 2024. Enmarcado dentro de la Estrategia Territorial de Inversiones, el CNI desempe\u00f1a un papel fundamental en la segunda edici\u00f3n la Expo Comayagua 2024; evento de gran envergadura que se lleva a cabo del 25 al 27 de julio en la ciudad de Comayagua.&nbsp; La Expo Comayagua es una plataforma dise\u00f1ada para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cni.hn\/en\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"CNI Honduras\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-12T23:57:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cni.hn\/wp-content\/uploads\/2024\/12\/c11e8d9d-fed9-44e2-9980-938e895b071f.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"bozabit\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"bozabit\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/\"},\"author\":{\"name\":\"bozabit\",\"@id\":\"https:\/\/cni.hn\/#\/schema\/person\/68eb275539b506f1d853d35702d20e61\"},\"headline\":\"El Consejo Nacional de Inversiones impulsa el desarrollo regional en la Expo Comayagua 2024\",\"datePublished\":\"2024-12-12T23:57:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/\"},\"wordCount\":616,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cni.hn\/#organization\"},\"image\":{\"@id\":\"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cni.hn\/wp-content\/uploads\/2024\/12\/c11e8d9d-fed9-44e2-9980-938e895b071f.jpg\",\"articleSection\":[\"Sala de Prensa\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/\",\"url\":\"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/\",\"name\":\"El Consejo Nacional de Inversiones impulsa el desarrollo regional en la Expo Comayagua 2024 - CNI Honduras\",\"isPartOf\":{\"@id\":\"https:\/\/cni.hn\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cni.hn\/wp-content\/uploads\/2024\/12\/c11e8d9d-fed9-44e2-9980-938e895b071f.jpg\",\"datePublished\":\"2024-12-12T23:57:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/#primaryimage\",\"url\":\"https:\/\/cni.hn\/wp-content\/uploads\/2024\/12\/c11e8d9d-fed9-44e2-9980-938e895b071f.jpg\",\"contentUrl\":\"https:\/\/cni.hn\/wp-content\/uploads\/2024\/12\/c11e8d9d-fed9-44e2-9980-938e895b071f.jpg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cni.hn\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Consejo Nacional de Inversiones impulsa el desarrollo regional en la Expo Comayagua 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cni.hn\/#website\",\"url\":\"https:\/\/cni.hn\/\",\"name\":\"CNI Honduras\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/cni.hn\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cni.hn\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cni.hn\/#organization\",\"name\":\"CNI Honduras\",\"url\":\"https:\/\/cni.hn\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/cni.hn\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cni.hn\/wp-content\/uploads\/2024\/10\/logo-cni.png\",\"contentUrl\":\"https:\/\/cni.hn\/wp-content\/uploads\/2024\/10\/logo-cni.png\",\"width\":390,\"height\":390,\"caption\":\"CNI Honduras\"},\"image\":{\"@id\":\"https:\/\/cni.hn\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cni.hn\/#\/schema\/person\/68eb275539b506f1d853d35702d20e61\",\"name\":\"bozabit\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/cni.hn\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/33e54dec0cd79fc4b5e911c15f836c46ec8d0e452ecd3ca5f707bce0a3540a3b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/33e54dec0cd79fc4b5e911c15f836c46ec8d0e452ecd3ca5f707bce0a3540a3b?s=96&d=mm&r=g\",\"caption\":\"bozabit\"},\"sameAs\":[\"https:\/\/cni.hn\"],\"url\":\"https:\/\/cni.hn\/en\/author\/bozabit\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Consejo Nacional de Inversiones impulsa el desarrollo regional en la Expo Comayagua 2024 - CNI Honduras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cni.hn\/en\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/","og_locale":"en_US","og_type":"article","og_title":"El Consejo Nacional de Inversiones impulsa el desarrollo regional en la Expo Comayagua 2024 - CNI Honduras","og_description":"Comayagua, 25 de julio 2024. Enmarcado dentro de la Estrategia Territorial de Inversiones, el CNI desempe\u00f1a un papel fundamental en la segunda edici\u00f3n la Expo Comayagua 2024; evento de gran envergadura que se lleva a cabo del 25 al 27 de julio en la ciudad de Comayagua.&nbsp; La Expo Comayagua es una plataforma dise\u00f1ada para [&hellip;]","og_url":"https:\/\/cni.hn\/en\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/","og_site_name":"CNI Honduras","article_published_time":"2024-12-12T23:57:24+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/cni.hn\/wp-content\/uploads\/2024\/12\/c11e8d9d-fed9-44e2-9980-938e895b071f.jpg","type":"image\/jpeg"}],"author":"bozabit","twitter_card":"summary_large_image","twitter_misc":{"Written by":"bozabit","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/#article","isPartOf":{"@id":"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/"},"author":{"name":"bozabit","@id":"https:\/\/cni.hn\/#\/schema\/person\/68eb275539b506f1d853d35702d20e61"},"headline":"El Consejo Nacional de Inversiones impulsa el desarrollo regional en la Expo Comayagua 2024","datePublished":"2024-12-12T23:57:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/"},"wordCount":616,"commentCount":0,"publisher":{"@id":"https:\/\/cni.hn\/#organization"},"image":{"@id":"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/cni.hn\/wp-content\/uploads\/2024\/12\/c11e8d9d-fed9-44e2-9980-938e895b071f.jpg","articleSection":["Sala de Prensa"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/","url":"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/","name":"El Consejo Nacional de Inversiones impulsa el desarrollo regional en la Expo Comayagua 2024 - CNI Honduras","isPartOf":{"@id":"https:\/\/cni.hn\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/#primaryimage"},"image":{"@id":"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/cni.hn\/wp-content\/uploads\/2024\/12\/c11e8d9d-fed9-44e2-9980-938e895b071f.jpg","datePublished":"2024-12-12T23:57:24+00:00","breadcrumb":{"@id":"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/#primaryimage","url":"https:\/\/cni.hn\/wp-content\/uploads\/2024\/12\/c11e8d9d-fed9-44e2-9980-938e895b071f.jpg","contentUrl":"https:\/\/cni.hn\/wp-content\/uploads\/2024\/12\/c11e8d9d-fed9-44e2-9980-938e895b071f.jpg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/cni.hn\/el-consejo-nacional-de-inversiones-impulsa-el-desarrollo-regional-en-la-expo-comayagua-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cni.hn\/"},{"@type":"ListItem","position":2,"name":"El Consejo Nacional de Inversiones impulsa el desarrollo regional en la Expo Comayagua 2024"}]},{"@type":"WebSite","@id":"https:\/\/cni.hn\/#website","url":"https:\/\/cni.hn\/","name":"CNI Honduras","description":"","publisher":{"@id":"https:\/\/cni.hn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cni.hn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/cni.hn\/#organization","name":"CNI Honduras","url":"https:\/\/cni.hn\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cni.hn\/#\/schema\/logo\/image\/","url":"https:\/\/cni.hn\/wp-content\/uploads\/2024\/10\/logo-cni.png","contentUrl":"https:\/\/cni.hn\/wp-content\/uploads\/2024\/10\/logo-cni.png","width":390,"height":390,"caption":"CNI Honduras"},"image":{"@id":"https:\/\/cni.hn\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cni.hn\/#\/schema\/person\/68eb275539b506f1d853d35702d20e61","name":"bozabit","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cni.hn\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/33e54dec0cd79fc4b5e911c15f836c46ec8d0e452ecd3ca5f707bce0a3540a3b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/33e54dec0cd79fc4b5e911c15f836c46ec8d0e452ecd3ca5f707bce0a3540a3b?s=96&d=mm&r=g","caption":"bozabit"},"sameAs":["https:\/\/cni.hn"],"url":"https:\/\/cni.hn\/en\/author\/bozabit\/"}]}},"_links":{"self":[{"href":"https:\/\/cni.hn\/en\/wp-json\/wp\/v2\/posts\/3516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cni.hn\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cni.hn\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cni.hn\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cni.hn\/en\/wp-json\/wp\/v2\/comments?post=3516"}],"version-history":[{"count":0,"href":"https:\/\/cni.hn\/en\/wp-json\/wp\/v2\/posts\/3516\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cni.hn\/en\/wp-json\/wp\/v2\/media\/3517"}],"wp:attachment":[{"href":"https:\/\/cni.hn\/en\/wp-json\/wp\/v2\/media?parent=3516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cni.hn\/en\/wp-json\/wp\/v2\/categories?post=3516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cni.hn\/en\/wp-json\/wp\/v2\/tags?post=3516"},{"taxonomy":"sector_relacionado","embeddable":true,"href":"https:\/\/cni.hn\/en\/wp-json\/wp\/v2\/sector_relacionado?post=3516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}